{"id":8160,"date":"2020-06-01T08:54:52","date_gmt":"2020-06-01T15:54:52","guid":{"rendered":"http:\/\/www.profelectro.info\/fm\/?p=8160"},"modified":"2020-06-01T08:54:52","modified_gmt":"2020-06-01T15:54:52","slug":"uxia-uxia-nas-cidades-da-lua-entrevista","status":"publish","type":"post","link":"https:\/\/www.profelectro.info\/fm\/2020\/06\/01\/uxia-uxia-nas-cidades-da-lua-entrevista\/","title":{"rendered":"Uxia &#8211; &#8220;Uxia Nas Cidades Da Lua&#8221; (entrevista)"},"content":{"rendered":"<div style=\"text-align: center;margin: 12px;\"><script type=\"text\/javascript\"><!--\ngoogle_ad_client = \"pub-9853707030319137\";\ngoogle_alternate_color = \"FFFFFF\";\ngoogle_ad_width = 300;\ngoogle_ad_height = 250;\ngoogle_ad_format = \"300x250_as\";\ngoogle_ad_type = \"text_image\";\ngoogle_ad_channel =\"\";\ngoogle_color_border = \"#FFFFFF\";\ngoogle_color_link = \"\";\ngoogle_color_bg = \"#FFFFFF\";\ngoogle_color_text = \"\";\ngoogle_color_url = \"\";\ngoogle_ui_features = \"rc:0\";\n\/\/--><\/script>\n<script type=\"text\/javascript\"\n  src=\"http:\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\">\n<\/script><\/div><p>Pop Rock >> Quarta-Feira, 15.04.1992<br \/>\n<center><br \/>\n<strong>UXIA NAS CIDADES DA LUA<\/strong><br \/>\n<\/center><br \/>\n<strong>No recente Festival Interc\u00e9ltico, a cantora galega Uxia, em apenas duas can\u00e7\u00f5es, redimiu \u201cBailia das Frores\u201d de todos os pecados. Com um \u00e1lbum de viagens solit\u00e1rias, \u201cEntre Cidades\u201d, agora editado, a antiga vocalista dos Na Lua d\u00e1 testemunho da Galiza ao resto do mundo.<\/strong><\/p>\n<p><center><br \/>\n<a href=\"http:\/\/www.profelectro.info\/fm\/?attachment_id=8161\" rel=\"attachment wp-att-8161\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.profelectro.info\/fm\/wp-content\/uploads\/2020\/06\/uxia.jpg\" alt=\"\" width=\"433\" height=\"813\" class=\"aligncenter size-full wp-image-8161\" srcset=\"https:\/\/www.profelectro.info\/fm\/wp-content\/uploads\/2020\/06\/uxia.jpg 433w, https:\/\/www.profelectro.info\/fm\/wp-content\/uploads\/2020\/06\/uxia-160x300.jpg 160w, https:\/\/www.profelectro.info\/fm\/wp-content\/uploads\/2020\/06\/uxia-53x100.jpg 53w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/a><br \/>\n<\/center><\/p>\n<p>Uxia abandonou os Na Lua. No contexto instrumental da banda, a voz soava a mais. Sem ela, a Lua escureceu e deixou de brilhar. Em Portugal, integrada na \u201cBailia das Frores\u201d, do portugu\u00eas Tent\u00fagal, mostrou que ela \u00e9 quem tem raz\u00e3o. Acabou de lan\u00e7ar no mercado o \u00e1lbum a solo \u201cEntre Cidades\u201d, que ter\u00e1 prov\u00e1vel distribui\u00e7\u00e3o entre n\u00f3s pela Mundo da Can\u00e7\u00e3o. Novos m\u00fasicos e novas ideias empurram-na para uma via interm\u00e9dia entre a tradi\u00e7\u00e3o galega e a modernidade. O P\u00daBLICO esteve com ela no Porto, para saber da lua, das cidades sem \u201ctextos anacr\u00f3nicos\u201d e da vida musical a norte do Minho.<br \/>\n<strong>P\u00daBLICO \u2013 Que motivos a levaram a abandonar os Na Lua?<\/strong><br \/>\nUXIA \u2013 Sobretudo na fase recente do grupo, comecei a ter d\u00favidas quanto \u00e0 minha fun\u00e7\u00e3o dentro dele. Os Na Lua sempre foram em primeiro lugar um grupo instrumental, que ocasionalmente trabalhou com a voz. A inclus\u00e3o da minha voz acabava por n\u00e3o resultar e por tornar-se secund\u00e1ria. Havia pouca coer\u00eancia. Isso notava-se, na diferen\u00e7a grande que existia entre os temas onde eu cantava e os instrumentais \u2013 era quase uma mudan\u00e7a de estilo.<br \/>\n<strong>P. \u2013 Depois do abandono, tem j\u00e1 algum novo projecto?<\/strong><br \/>\nR. \u2013 Sim, estou a trabalhar com um grupo de m\u00fasicos com quem posso fazer aquilo que quero: C\u00e1ndido Lorenzo, que toca clarinete, flauta e \u201cgaita\u201d [gaita-de-foles]; Ant\u00f3n Rodriguez, dos Na Lua, \u201cgaita\u201d, flauta e saxofone; Xos\u00e9 Paz Ant\u00f3n, tamb\u00e9m dos Na Lua, bateria e guitarra el\u00e9ctrica e Natcho Munoz, teclados.<br \/>\n<strong>P. \u2013 Os mesmos que participam na sua estreia discogr\u00e1fica a solo, \u201cEntre Cidades\u201d?<\/strong><br \/>\nR. \u2013 N\u00e3o, este disco foi feito praticamente s\u00f3 com o Quico [Francisco Alvarez] e o Xos\u00e9 Paz Ant\u00f3n, dos Na Lua, e o J\u00falio Pereira, que toca sintetizador num dos temas. \u00c9 um disco de procura de uma linha musical pr\u00f3pria, que pode soar um pouco frio por haver poucos m\u00fasicos e instrumenta\u00e7\u00e3o.<\/p>\n<p><strong>O Despertar Das Vozes<\/strong><\/p>\n<p><strong>P. \u2013 \u201cEntre Cidades\u201d tem pouco que ver com a m\u00fasica tradicional\u2026<\/strong><br \/>\nR. \u2013 Sim, \u00e9 verdade, se bem que nalguns casos os timbres da voz derivem da\u00ed e noutros apare\u00e7a uma ou outra melodia popular. No futuro, penso que nos iremos voltar mais para a m\u00fasica popular. Ou pelo menos procurar uma via interm\u00e9dia. O problema diz respeito, sobretudo, aos textos populares, que acabam \u00e0s vezes por ser um pouco anacr\u00f3nicos. Por vezes n\u00e3o me sinto identificada com as palavras. Neste momento estou eu pr\u00f3pria a escrever alguns poemas, algo que, por uma esp\u00e9cie de pudor, nunca fiz anteriormente.<br \/>\n<strong>P. \u2013 Qual a sua posi\u00e7\u00e3o sobre a m\u00fasica tradicional que se faz hoje na Galiza, em que de uma primeira fase de forte componente nacionalista se passou para ced\u00eancias sucessivas ao rock, como aconteceu por exemplo no recente \u201cInterc\u00e9ltico\u201d, com os Matto Congrio, ou os pr\u00f3prios Na Lua, h\u00e1 dois anos?<\/strong><br \/>\nR. \u2013 S\u00e3o op\u00e7\u00f5es, todas elas respeit\u00e1veis. De certa forma, ningu\u00e9m sabe muito bem para onde ir. Nalguns casos, experimentou-se sem se aprofundar mais a sua m\u00fasica at\u00e9 chegar a um estilo pessoal que n\u00e3o teria for\u00e7osamente de se incluir no lugar-comum do \u201cfolk rock\u201d. Mas \u00e9 de toda a justi\u00e7a frisar que na Galiza est\u00e3o a surgir grupos com novas ideias \u2013 os Armeguin, por exemplo [editaram o \u00e1lbum \u201cViaxantes da Luz\u201d, uma esp\u00e9cie de \u201cnew age\u201d tradicional galega]. Por outro lado, ressurgem um pouco por toda a Galiza as \u201cpandeiretadas\u201d tradicionais que estavam esquecidas e os Milladoiro recuperaram em \u201cGalicia no Pais das Maravilhas\u201d. Tamb\u00e9m se assiste ao despertar das vozes, t\u00e3o menosprezadas na Galiza.<br \/>\n<strong>P. \u2013 Como explica a predomin\u00e2ncia dos grupos instrumentais no panorama da m\u00fasica tradicional galega?<\/strong><br \/>\nR. \u2013 O que se passa \u00e9 que muitos grupos se inspiraram nos Milladoiro, que s\u00e3o exclusivamente instrumentais. Mas, para um pa\u00eds que pretenda fazer uma m\u00fasica que se possa considerar sua, \u00e9 imprescind\u00edvel cantar.<\/p>\n<p><strong>Coliga\u00e7\u00e3o Galaico-Portuguesa<\/strong><\/p>\n<p><strong>P. \u2013 Fala-se muito da aproxima\u00e7\u00e3o e da identidade cultural entre o Norte de Portugal e a Galiza, mas na pr\u00e1tica pouco tem sido feito no sentido de uma colabora\u00e7\u00e3o efectiva e regular entre as duas regi\u00f5es.<\/strong><br \/>\nR. \u2013 Sou uma grande defensora da liga\u00e7\u00e3o entre Galiza e Portugal, mas reconhe\u00e7o que pouco tem sido feito por ambas as partes. No meu caso e dos Na Lua, desde o in\u00edcio que houve contactos e refer\u00eancias portuguesas: o maior \u00eaxito dos Na Lua chama-se \u201cDublin \/ Coimbra\u201d. Em \u201cEstrela de Maio\u201d, h\u00e1 o tema \u201cAs Flores de Viana\u201d e uma vers\u00e3o do Zeca Afonso \u201cMaio Maduro Maio\u201d. Nas \u201cOndas do Mar de Vigo\u201d, o produtor foi J\u00falio Pereira e o Fausto cantou uma can\u00e7\u00e3o de parceria comigo. No meu disco a solo, o J\u00falio Pereira volta a estar presente e h\u00e1 uma can\u00e7\u00e3o sobre Lisboa\u2026 Em termos de m\u00fasica popular, Portugal \u00e9 dos pa\u00edses mais ricos que tenho conhecido. Vou propor ao Tent\u00fagal fazer uma esp\u00e9cie de circuito entre a Galiza e Portugal, com espect\u00e1culos meus e dos Vai de Roda.<br \/>\n<strong>P. \u2013 Parece existir uma certa desuni\u00e3o entre os m\u00fasicos galegos que impede uma maior projec\u00e7\u00e3o da m\u00fasica galega no mundo.<\/strong><br \/>\nR. \u2013 Fundou-se em tempos, na Galiza, uma associa\u00e7\u00e3o que procurava criar uma plataforma de entendimento entre os m\u00fasicos. \u00c0 terceira reuni\u00e3o, a associa\u00e7\u00e3o fechou\u2026 os m\u00fasicos galegos s\u00e3o um pouco an\u00e1rquicos, e tudo acabou por ficar muito confuso. De qualquer forma, foi a primeira vez que na Galiza se juntaram cerca de 15 grupos para discutir ao redor de uma mesa. Quanto \u00e0 televis\u00e3o e \u00e0 r\u00e1dio oficiais, marginalizam por completo esta m\u00fasica. Na Catalunha houve um protesto p\u00fablico da Maria Del Mar Bonnet. Aqui h\u00e1 urg\u00eancia em fazer a mesma coisa.<br \/>\n<strong>P. \u2013 Um programa como Mar A Mar, que passou durante algumas noites na RTP, serve de algum modo os interesses da genu\u00edna m\u00fasica da Galiza?<\/strong><br \/>\nR. \u2013 Era um programa mau. Muitos grupos galegos, a maior parte de segunda fila, passaram por a\u00ed, mas realmente n\u00e3o faz sentido p\u00f4r um \u201cballet\u201d de \u201cn\u00e3o sei qu\u00ea\u201d no mesmo cen\u00e1rio de um grupo folk, que normalmente sa\u00eda sempre desvalorizado ali metido no meio. Era necess\u00e1rio que a televis\u00e3o tivesse mais imagina\u00e7\u00e3o, um programa do tipo do vosso Outras M\u00fasicas. O Mar A Mar dava uma imagem equivocada da Galiza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pop Rock >> Quarta-Feira, 15.04.1992 UXIA NAS CIDADES DA LUA No recente Festival Interc\u00e9ltico, a cantora galega Uxia, em apenas duas can\u00e7\u00f5es, redimiu \u201cBailia das Frores\u201d de todos os pecados. Com um \u00e1lbum de viagens solit\u00e1rias, \u201cEntre Cidades\u201d, agora editado, a antiga vocalista dos Na Lua d\u00e1 testemunho da Galiza ao resto do mundo. Uxia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[722,2564,179,68],"tags":[2600],"class_list":["post-8160","post","type-post","status-publish","format-standard","hentry","category-celtica","category-entrevistas-1992","category-etno","category-world","tag-uxia"],"views":1206,"_links":{"self":[{"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/posts\/8160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/comments?post=8160"}],"version-history":[{"count":1,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/posts\/8160\/revisions"}],"predecessor-version":[{"id":8162,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/posts\/8160\/revisions\/8162"}],"wp:attachment":[{"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/media?parent=8160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/categories?post=8160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.profelectro.info\/fm\/wp-json\/wp\/v2\/tags?post=8160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}